{"id":25855,"date":"2022-11-19T22:01:22","date_gmt":"2022-11-19T22:01:22","guid":{"rendered":"https:\/\/quizzical-merkle.109-228-39-111.plesk.page\/?page_id=25855"},"modified":"2024-04-02T07:21:47","modified_gmt":"2024-04-02T07:21:47","slug":"distributorship-and-channel-management","status":"publish","type":"page","link":"https:\/\/www.unveilcare.com\/index.php\/distributorship-and-channel-management\/","title":{"rendered":"Distributorship and Channel Management\u200b\u200b"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25855\" class=\"elementor elementor-25855\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34ce7398 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"34ce7398\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c86fa5f\" data-id=\"5c86fa5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c86428d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c86428d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ac62d9\" data-id=\"5ac62d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-019f17b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"019f17b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c562683\" data-id=\"c562683\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a9c80b\" data-id=\"3a9c80b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ccba73e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ccba73e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-634b098b\" data-id=\"634b098b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77bd3d3b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"77bd3d3b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Distributorship & Channel Management<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d78430e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d78430e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68f4b1e4 elementor-invisible\" data-id=\"68f4b1e4\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7bede5 elementor-widget elementor-widget-text-editor\" data-id=\"c7bede5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21c6e5f8\" data-id=\"21c6e5f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d9e1ad1 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2d9e1ad1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32e46455 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32e46455\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-780ca462\" data-id=\"780ca462\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46563ec elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"46563ec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/www.unveilcare.com\/wp-content\/uploads\/2024\/04\/distribution-management_ok.jpg\" class=\"attachment-large size-large wp-image-28300\" alt=\"\" srcset=\"https:\/\/www.unveilcare.com\/wp-content\/uploads\/2024\/04\/distribution-management_ok.jpg 1020w, https:\/\/www.unveilcare.com\/wp-content\/uploads\/2024\/04\/distribution-management_ok-300x169.jpg 300w, https:\/\/www.unveilcare.com\/wp-content\/uploads\/2024\/04\/distribution-management_ok-768x432.jpg 768w, https:\/\/www.unveilcare.com\/wp-content\/uploads\/2024\/04\/distribution-management_ok-600x338.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ac656af\" data-id=\"2ac656af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e571c01 elementor-widget elementor-widget-text-editor\" data-id=\"1e571c01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Support commercial model entry decisions on channel strategy \u2013 direct vs. distributor vs. hybrid models \u2013 based on market specific needs, economics, risks<\/p><p>Help manufacturers on their channel management strategies. from design, implementation to management.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-211aabe elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"211aabe\" data-element_type=\"section\" id=\"xs_accor_side_curve\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-105e2529\" data-id=\"105e2529\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11720c27\" data-id=\"11720c27\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e19af40 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"4e19af40\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary side-curve\" id=\"accordion-6a97cfe4e6202\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-4e19af40\">\n                        <a href=\"#collapse-bc228306a97cfe4e6202\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bc228306a97cfe4e6202\" aria-expanded=\"false\" aria-controls=\"Collapse-bc228306a97cfe4e6202\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                                                                        <i class=\"icon icon-arrow-down icon-open icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                                                                        <i class=\"icon icon-arrow-up icon-closed icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Channel Management Strategy\u200b<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bc228306a97cfe4e6202\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-4e19af40\" data-parent=\"#accordion-6a97cfe4e6202\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ul><li>The Role of Channel Management<\/li><li>Channel Strategy<\/li><li>Goals &amp; Objectives<\/li><li>Markets Analysis &amp; Targeting<\/li><li>End Users<\/li><li>Channel Types<\/li><li>Sales Coverage Strategy<\/li><li>Roles &amp; Responsabilities<\/li><li>Profitable Compliant Growth<\/li><li>Channel Management Strategy Review<\/li><\/ul>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-4e19af40\">\n                        <a href=\"#collapse-8417e716a97cfe4e6202\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-8417e716a97cfe4e6202\" aria-expanded=\"false\" aria-controls=\"Collapse-8417e716a97cfe4e6202\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                                                                        <i class=\"icon icon-arrow-down icon-open icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                                                                        <i class=\"icon icon-arrow-up icon-closed icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Channel Management Concepts\u200b<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-8417e716a97cfe4e6202\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-4e19af40\" data-parent=\"#accordion-6a97cfe4e6202\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ul><li>Economics &amp; Compensation<\/li><li>Channel Programs &amp; Technology<\/li><li>Channel Power\/Window\/Mindshare<\/li><li>Channel Growability<\/li><li>Conflict Management\/Rules of Engagement<\/li><li>Channel Management Concepts Review<\/li><\/ul>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-4e19af40\">\n                        <a href=\"#collapse-3dad4e06a97cfe4e6202\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3dad4e06a97cfe4e6202\" aria-expanded=\"false\" aria-controls=\"Collapse-3dad4e06a97cfe4e6202\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                                                                        <i class=\"icon icon-arrow-down icon-open icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                                                                        <i class=\"icon icon-arrow-up icon-closed icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Channel Management Process\u200b<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3dad4e06a97cfe4e6202\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-4e19af40\" data-parent=\"#accordion-6a97cfe4e6202\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ul><li>Define Coverage<\/li><li>Target &amp; Recruit<\/li><li>Engage &amp; Ramp-up<\/li><li>Train &amp; Support<\/li><li>Manage &amp; Grow<\/li><li>Optimize<\/li><li>Channel Management process Review<\/li><li>Personal Action Plan<\/li><\/ul>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-4e19af40\">\n                        <a href=\"#collapse-a4ab01f6a97cfe4e6202\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a4ab01f6a97cfe4e6202\" aria-expanded=\"false\" aria-controls=\"Collapse-a4ab01f6a97cfe4e6202\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                                                                        <i class=\"icon icon-arrow-down icon-open icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                                                                        <i class=\"icon icon-arrow-up icon-closed icon-left\" aria-hidden=\"true\"><\/i>\n                                                                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Distributorship\u200b<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a4ab01f6a97cfe4e6202\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-4e19af40\" data-parent=\"#accordion-6a97cfe4e6202\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ul><li>Coverage (See more)<\/li><li>Competitiveness (Win more)<\/li><li>Customer (Retain more)<\/li><\/ul>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Distributorship &#038; Channel Management Support commercial model entry decisions on channel strategy \u2013 direct vs. distributor vs. hybrid models \u2013 based on market specific needs, economics, risks Help manufacturers on their channel management strategies. from design, implementation to management. Channel Management Strategy\u200b The Role of Channel Management Channel Strategy Goals &amp; Objectives Markets Analysis &amp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-25855","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/pages\/25855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/comments?post=25855"}],"version-history":[{"count":102,"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/pages\/25855\/revisions"}],"predecessor-version":[{"id":28335,"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/pages\/25855\/revisions\/28335"}],"wp:attachment":[{"href":"https:\/\/www.unveilcare.com\/index.php\/wp-json\/wp\/v2\/media?parent=25855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}